{"id":141507,"date":"2021-11-30T10:34:25","date_gmt":"2021-11-30T09:34:25","guid":{"rendered":"https:\/\/www.assofide.ch\/immobilien\/929480fr-res-passetto-19-ref-83-107\/"},"modified":"2026-05-13T03:30:40","modified_gmt":"2026-05-13T01:30:40","slug":"929480fr-res-passetto-19-ref-83-107","status":"publish","type":"casawp_property","link":"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/","title":{"rendered":"Res. Passetto 19 (ref. 83-107)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Res. Passetto 19 (ref. 83-107)<\/p>\n","protected":false},"author":1,"featured_media":151118,"parent":0,"menu_order":141,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"casawp_category":[384],"casawp_feature":[],"casawp_utility":[305],"casawp_location":[309,410,376],"casawp_salestype":[318],"casawp_availability":[308],"casawp_region":[370],"class_list":["post-141507","casawp_property","type-casawp_property","status-publish","has-post-thumbnail","hentry","casawp_category-parking","casawp_utility-residential","casawp_location-country_ch","casawp_location-locality_solduno","casawp_location-region_ti","casawp_salestype-rent","casawp_availability-active","casawp_region-locarnese"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Res. Passetto 19 (ref. 83-107) - Assofide SA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Res. Passetto 19 (ref. 83-107) - Assofide SA\" \/>\n<meta property=\"og:description\" content=\"Res. Passetto 19 (ref. 83-107)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/\" \/>\n<meta property=\"og:site_name\" content=\"Assofide SA\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T01:30:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/immobilien\\\/929480fr-res-passetto-19-ref-83-107\\\/\",\"url\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/immobilien\\\/929480fr-res-passetto-19-ref-83-107\\\/\",\"name\":\"Res. Passetto 19 (ref. 83-107) - Assofide SA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/immobilien\\\/929480fr-res-passetto-19-ref-83-107\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/immobilien\\\/929480fr-res-passetto-19-ref-83-107\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-10116\\\/property-929480\\\/083-107.01_2019_12_23_1739.jpg?p=xl\",\"datePublished\":\"2021-11-30T09:34:25+00:00\",\"dateModified\":\"2026-05-13T01:30:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/immobilien\\\/929480fr-res-passetto-19-ref-83-107\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/immobilien\\\/929480fr-res-passetto-19-ref-83-107\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/immobilien\\\/929480fr-res-passetto-19-ref-83-107\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-10116\\\/property-929480\\\/083-107.01_2019_12_23_1739.jpg?p=xl\",\"contentUrl\":\"https:\\\/\\\/cdn.casasoft.com\\\/media\\\/provider-10116\\\/property-929480\\\/083-107.01_2019_12_23_1739.jpg?p=xl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/immobilien\\\/929480fr-res-passetto-19-ref-83-107\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propri\u00e9t\u00e9s\",\"item\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/immobilien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Res. Passetto 19 (ref. 83-107)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/\",\"name\":\"Assofide SA\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/#organization\",\"name\":\"Assofide SA\",\"url\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.assofide.ch\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/12\\\/assofide_logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.assofide.ch\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2025\\\/12\\\/assofide_logo.svg\",\"width\":600,\"height\":666,\"caption\":\"Assofide SA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.assofide.ch\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Res. Passetto 19 (ref. 83-107) - Assofide SA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/","og_locale":"fr_FR","og_type":"article","og_title":"Res. Passetto 19 (ref. 83-107) - Assofide SA","og_description":"Res. Passetto 19 (ref. 83-107)","og_url":"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/","og_site_name":"Assofide SA","article_modified_time":"2026-05-13T01:30:40+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/","url":"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/","name":"Res. Passetto 19 (ref. 83-107) - Assofide SA","isPartOf":{"@id":"https:\/\/www.assofide.ch\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/#primaryimage"},"image":{"@id":"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/#primaryimage"},"thumbnailUrl":"https:\/\/cdn.casasoft.com\/media\/provider-10116\/property-929480\/083-107.01_2019_12_23_1739.jpg?p=xl","datePublished":"2021-11-30T09:34:25+00:00","dateModified":"2026-05-13T01:30:40+00:00","breadcrumb":{"@id":"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/#primaryimage","url":"https:\/\/cdn.casasoft.com\/media\/provider-10116\/property-929480\/083-107.01_2019_12_23_1739.jpg?p=xl","contentUrl":"https:\/\/cdn.casasoft.com\/media\/provider-10116\/property-929480\/083-107.01_2019_12_23_1739.jpg?p=xl"},{"@type":"BreadcrumbList","@id":"https:\/\/www.assofide.ch\/fr\/immobilien\/929480fr-res-passetto-19-ref-83-107\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.assofide.ch\/fr\/"},{"@type":"ListItem","position":2,"name":"Propri\u00e9t\u00e9s","item":"https:\/\/www.assofide.ch\/fr\/immobilien\/"},{"@type":"ListItem","position":3,"name":"Res. Passetto 19 (ref. 83-107)"}]},{"@type":"WebSite","@id":"https:\/\/www.assofide.ch\/fr\/#website","url":"https:\/\/www.assofide.ch\/fr\/","name":"Assofide SA","description":"","publisher":{"@id":"https:\/\/www.assofide.ch\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.assofide.ch\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.assofide.ch\/fr\/#organization","name":"Assofide SA","url":"https:\/\/www.assofide.ch\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.assofide.ch\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.assofide.ch\/wp-content\/uploads\/sites\/5\/2025\/12\/assofide_logo.svg","contentUrl":"https:\/\/www.assofide.ch\/wp-content\/uploads\/sites\/5\/2025\/12\/assofide_logo.svg","width":600,"height":666,"caption":"Assofide SA"},"image":{"@id":"https:\/\/www.assofide.ch\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/casawp_property\/141507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/casawp_property"}],"about":[{"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/types\/casawp_property"}],"author":[{"embeddable":true,"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/comments?post=141507"}],"version-history":[{"count":0,"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/casawp_property\/141507\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/media\/151118"}],"wp:attachment":[{"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/media?parent=141507"}],"wp:term":[{"taxonomy":"casawp_category","embeddable":true,"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/casawp_category?post=141507"},{"taxonomy":"casawp_feature","embeddable":true,"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/casawp_feature?post=141507"},{"taxonomy":"casawp_utility","embeddable":true,"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/casawp_utility?post=141507"},{"taxonomy":"casawp_location","embeddable":true,"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/casawp_location?post=141507"},{"taxonomy":"casawp_salestype","embeddable":true,"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/casawp_salestype?post=141507"},{"taxonomy":"casawp_availability","embeddable":true,"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/casawp_availability?post=141507"},{"taxonomy":"casawp_region","embeddable":true,"href":"https:\/\/www.assofide.ch\/fr\/wp-json\/wp\/v2\/casawp_region?post=141507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}